{"id":23320,"date":"2025-04-13T17:39:34","date_gmt":"2025-04-13T17:39:34","guid":{"rendered":"https:\/\/researchchemicalhub.com\/?post_type=product&#038;p=23320"},"modified":"2025-10-30T10:13:07","modified_gmt":"2025-10-30T10:13:07","slug":"flualprazolam-puur","status":"publish","type":"product","link":"https:\/\/researchchemicalhub.com\/fr\/shop\/verboden\/flualprazolam-puur\/","title":{"rendered":"Flualprazolam pur"},"content":{"rendered":"<h2><span data-sheets-value=\"{\" data-sheets-userformat=\"{\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Flualprazolam<\/span><\/span><\/span><\/h2>\n<p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Flualprazolam<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> is a substance that is only sold for research purposes and is therefore not intended for consumption.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Flualprazolam remains stable for up to 2 years when stored in the correct environment. Flualprazolam is intended for research purposes and not for consumption. Therefore, it is important to store the product out of the reach of children and pets. 2C-E<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">We offer high-quality research chemicals at a fair price. Your order ships within 24 hours every day. Order <\/span><\/span><em><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Flualprazolam<\/span><\/span><\/em><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> safely and quickly through !Buy 3-CMC (3-Chloromethcathinone)<\/span><\/span><\/p>\n<h3><span data-sheets-value=\"{\" data-sheets-userformat=\"{\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Flualprazolam properties<\/span><\/span><\/span><\/h3>\n<p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Synonym:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> Fluclazolam <\/span><\/span><br \/>\n<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">CAS Number:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> 28910-91-0 <\/span><\/span><br \/>\n<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Formula:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> 8-chloro-6-(2-fluorophenyl)-1-methyl-4H-[1,2,4]triazolo[4,3-a][1,4]benzodiazepine <\/span><\/span><br \/>\n<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Molar mass:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> 326.8 g\/mol <\/span><\/span><br \/>\n<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Purity:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> &gt;97%<\/span><\/span><\/p>\n<h3><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Hazard statement<\/span><\/span><\/h3>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Flualprazolam may cause respiratory irritation. <\/span><\/span><br \/>\n<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Flualprazolam may cause eye irritation. <\/span><\/span><br \/>\n<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Discharging research chemicals into the environment is prohibited.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Flualprazolam IN EYES: Rinse eyes gently with water for five minutes. Remove contact lenses, if present and easy to do. 3-MEO-PCP<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Flualprazolam IN CONTACT WITH SKIN: Wash skin with soap and water.4-HO-MET Fumarate<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">IF INHALED: Remove victim to fresh air and keep victim in a position comfortable for breathing.3-MEC<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<h3><span data-sheets-value=\"{\" data-sheets-userformat=\"{\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Flualprazolam Pure properties<\/span><\/span><\/span><\/h3>\n<p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Synonym:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> Fluclazolam <\/span><\/span><br \/>\n<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">CAS Number:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> 28910-91-0 <\/span><\/span><br \/>\n<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Formula:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> 8-chloro-6-(2-fluorophenyl)-1-methyl-4H-[1,2,4]triazolo[4,3-a][1,4]benzodiazepine <\/span><\/span><br \/>\n<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Molar mass:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> 326.8 g\/mol <\/span><\/span><br \/>\n<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Purity:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> &gt;97%<\/span><\/span><\/p>\n","protected":false},"featured_media":28523,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[488],"product_tag":[1137,1138,1212,1213,326],"class_list":{"0":"post-23320","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-verboden","7":"product_tag-flualprazolam","8":"product_tag-flualprazolam-kopen","9":"product_tag-flualprazolam-puur","10":"product_tag-flualprazolam-puur-kopen","11":"product_tag-nl","13":"first","14":"instock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/researchchemicalhub.com\/fr\/wp-json\/wp\/v2\/product\/23320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/researchchemicalhub.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/researchchemicalhub.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/researchchemicalhub.com\/fr\/wp-json\/wp\/v2\/comments?post=23320"}],"version-history":[{"count":4,"href":"https:\/\/researchchemicalhub.com\/fr\/wp-json\/wp\/v2\/product\/23320\/revisions"}],"predecessor-version":[{"id":28747,"href":"https:\/\/researchchemicalhub.com\/fr\/wp-json\/wp\/v2\/product\/23320\/revisions\/28747"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/researchchemicalhub.com\/fr\/wp-json\/wp\/v2\/media\/28523"}],"wp:attachment":[{"href":"https:\/\/researchchemicalhub.com\/fr\/wp-json\/wp\/v2\/media?parent=23320"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/researchchemicalhub.com\/fr\/wp-json\/wp\/v2\/product_brand?post=23320"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/researchchemicalhub.com\/fr\/wp-json\/wp\/v2\/product_cat?post=23320"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/researchchemicalhub.com\/fr\/wp-json\/wp\/v2\/product_tag?post=23320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}